{"id":32489,"date":"2025-05-28T15:55:11","date_gmt":"2025-05-28T13:55:11","guid":{"rendered":"https:\/\/www.hs-nordhausen.de\/?post_type=dokumente&#038;p=32489"},"modified":"2025-05-28T15:55:14","modified_gmt":"2025-05-28T13:55:14","slug":"module-networking-and-capacity-overview","status":"publish","type":"dokumente","link":"https:\/\/www.hs-nordhausen.de\/en\/dokumente\/modulvernetzungs-und-kapazitaetsueberblick\/","title":{"rendered":"Module networking and capacity overview"},"content":{"rendered":"<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/03\/Modulvernetzungs-und_Kapazitaetsueberblick.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of module networking and capacity overview.\"><\/object><a id=\"wp-block-file--media-4c5793e2-1c55-46a0-a832-a6f7ecb70ea8\" href=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/03\/Modulvernetzungs-und_Kapazitaetsueberblick.pdf\">Module networking and capacity overview<\/a><\/div>","protected":false},"author":1,"parent":0,"menu_order":0,"template":"","meta":{"_piecal_is_recurring":false,"_piecal_recurring_interval":1,"_piecal_recurring_frequency":"","_piecal_recurring_exact_position":false,"_piecal_recurring_end":"","_piecal_color":"","_piecal_text_color":"","_piecal_global_color_master":false,"_piecal_rsets":"[]","_piecal_is_event":false,"_piecal_start_date":"","_piecal_end_date":"","_piecal_is_allday":false,"greyd_block_editor_preview":[],"pgc_sgb_lightbox_settings":""},"dokumente_category":[3013],"dokumente_tag":[],"dokumente_geltungsbereich":[2131],"zielgruppen":[1976,1873,1874],"kontakt-zuordnung":[],"projekt":[1422],"studienbereich":[806],"stg-zuordnung":[638,640,649,650],"zusatzbereiche":[842,844,854,853],"fachbereich":[591],"wf_dokumente_folders":[2986],"ppma_author":[1400],"class_list":["post-32489","dokumente","type-dokumente","status-publish","hentry","dokumente_category-modulhandbuch","dokumente_geltungsbereich-n-a","zielgruppen-lehrende","zielgruppen-studieninteressierte","zielgruppen-studierende","projekt-n-a","studienbereich-betriebswirtschaftslehre","stg-zuordnung-bwl","stg-zuordnung-dpm","stg-zuordnung-icm","stg-zuordnung-ibw","zusatzbereiche-bwl","zusatzbereiche-dpm","zusatzbereiche-ibw","zusatzbereiche-icm","fachbereich-fb-wirtschafts-und-sozialwissenschaften"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:27:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"dokumente_category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/dokumente\/32489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/dokumente"}],"about":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/types\/dokumente"}],"author":[{"embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media?parent=32489"}],"wp:term":[{"taxonomy":"dokumente_category","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/dokumente_category?post=32489"},{"taxonomy":"dokumente_tag","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/dokumente_tag?post=32489"},{"taxonomy":"dokumente_geltungsbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/dokumente_geltungsbereich?post=32489"},{"taxonomy":"zielgruppen","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/zielgruppen?post=32489"},{"taxonomy":"kontakt-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/kontakt-zuordnung?post=32489"},{"taxonomy":"projekt","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/projekt?post=32489"},{"taxonomy":"studienbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studienbereich?post=32489"},{"taxonomy":"stg-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/stg-zuordnung?post=32489"},{"taxonomy":"zusatzbereiche","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/zusatzbereiche?post=32489"},{"taxonomy":"fachbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/fachbereich?post=32489"},{"taxonomy":"wf_dokumente_folders","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/wf_dokumente_folders?post=32489"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/ppma_author?post=32489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}