{"id":32104,"date":"2025-05-16T10:26:57","date_gmt":"2025-05-16T08:26:57","guid":{"rendered":"https:\/\/www.hs-nordhausen.de\/?post_type=pressemitteilungen&#038;p=32104"},"modified":"2025-05-16T10:27:02","modified_gmt":"2025-05-16T08:27:02","slug":"start-ups-introduce-themselves-demo-day-at-the-university-3","status":"publish","type":"pressemitteilungen","link":"https:\/\/www.hs-nordhausen.de\/en\/pressemitteilungen\/start-ups-stellen-sich-vor-demo-day-an-der-hochschule-3\/","title":{"rendered":"START-UPS INTRODUCES ITSELF - Demo Day at the university"},"content":{"rendered":"<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/05\/DEMODAY_2025_Header-1024x576.png\" alt=\"a person wearing a gas mask\" class=\"wp-image-32105\" title=\"\" srcset=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/05\/DEMODAY_2025_Header-1024x576.png 1024w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/05\/DEMODAY_2025_Header-300x169.png 300w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/05\/DEMODAY_2025_Header-150x84.png 150w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/05\/DEMODAY_2025_Header-768x432.png 768w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/05\/DEMODAY_2025_Header-1536x864.png 1536w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/05\/DEMODAY_2025_Header-18x10.png 18w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/05\/DEMODAY_2025_Header-24x14.png 24w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/05\/DEMODAY_2025_Header.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Poster motif for the hike Demo Day on 24 May 2025 as part of the Long Night of Science at Nordhausen University of Applied Sciences. The event presents innovative start-up pitches, audience award and networking in the Audimax. (Graphic: hike \/ Nordhausen University of Applied Sciences)<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Poster motif for the hike Demo Day on 24 May 2025 as part of the Long Night of Science at Nordhausen University of Applied Sciences. The event presents innovative start-up pitches, audience award and networking in the Audimax. (Graphic: hike \/ Nordhausen University of Applied Sciences)<\/p>","protected":false},"featured_media":32105,"template":"","meta":{"_piecal_is_recurring":false,"_piecal_recurring_interval":1,"_piecal_recurring_frequency":"","_piecal_recurring_exact_position":false,"_piecal_recurring_end":"","_piecal_color":"","_piecal_text_color":"","_piecal_global_color_master":false,"_piecal_rsets":"[]","_piecal_is_event":true,"_piecal_start_date":"2025-05-16T10:24:23","_piecal_end_date":"2025-05-16T10:24:25","_piecal_is_allday":false,"greyd_block_editor_preview":[],"pgc_sgb_lightbox_settings":""},"pressemitteilungen_category":[1298],"pressemitteilungen_tag":[2985],"zielgruppen":[1870],"kontakt-zuordnung":[2001],"projekt":[1425],"studienbereich":[868],"institut-oder-einric":[736],"stg-zuordnung":[696],"fachbereich":[804],"wf_pressemitteilungen_folders":[2657],"ppma_author":[1810],"class_list":["post-32104","pressemitteilungen","type-pressemitteilungen","status-publish","has-post-thumbnail","hentry","pressemitteilungen_category-pm-aktuell","pressemitteilungen_tag-demo-day","zielgruppen-alle-interessierten","kontakt-zuordnung-n-a","projekt-hike","studienbereich-n-a","institut-oder-einric-n-a","stg-zuordnung-n-a","fachbereich-n-a"],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen\/32104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen"}],"about":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/types\/pressemitteilungen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media\/32105"}],"wp:attachment":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media?parent=32104"}],"wp:term":[{"taxonomy":"pressemitteilungen_category","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen_category?post=32104"},{"taxonomy":"pressemitteilungen_tag","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen_tag?post=32104"},{"taxonomy":"zielgruppen","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/zielgruppen?post=32104"},{"taxonomy":"kontakt-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/kontakt-zuordnung?post=32104"},{"taxonomy":"projekt","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/projekt?post=32104"},{"taxonomy":"studienbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studienbereich?post=32104"},{"taxonomy":"institut-oder-einric","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/institut-oder-einric?post=32104"},{"taxonomy":"stg-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/stg-zuordnung?post=32104"},{"taxonomy":"fachbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/fachbereich?post=32104"},{"taxonomy":"wf_pressemitteilungen_folders","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/wf_pressemitteilungen_folders?post=32104"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/ppma_author?post=32104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}