{"id":36782,"date":"2025-11-10T09:54:14","date_gmt":"2025-11-10T08:54:14","guid":{"rendered":"https:\/\/www.hs-nordhausen.de\/?post_type=pressemitteilungen&#038;p=36782"},"modified":"2025-11-10T09:54:16","modified_gmt":"2025-11-10T08:54:16","slug":"international-students-and-company-representatives-network-at-the-cricket-match","status":"publish","type":"pressemitteilungen","link":"https:\/\/www.hs-nordhausen.de\/en\/pressemitteilungen\/internationale-studierende-und-unternehmensvertreter-vernetzen-sich-beim-cricket-spiel\/","title":{"rendered":"International students and company representatives network at the cricket match"},"content":{"rendered":"\n<p><\/p>\n\n\n<div class=\"pgc-sgb-cb wp-block-pgcsimplygalleryblock-viewer  \" data-gallery-id=\"edf63700\"><div class=\"sgb-preloader\" id=\"pr_edf63700\">\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div><\/div><div class=\"simply-gallery-amp pgc_sgb_slider \"><noscript><div class=\"sgb-gallery\"><div class=\"sgb-item\"><a href=\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36787\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7950-300x225.jpg\" srcset=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7950-300x225.jpg 300w,https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7950-2048x1536.jpg 2048w,https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7950-scaled.jpg 2560w\" sizes=\"auto, 250px\" title=\"\"><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36786\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"247\" height=\"300\" loading=\"lazy\" src=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7933-247x300.jpg\" srcset=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7933-247x300.jpg 247w,https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7933-1685x2048.jpg 1685w,https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7933-scaled.jpg 2107w\" sizes=\"auto, 250px\" title=\"\"><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36785\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"237\" height=\"300\" loading=\"lazy\" src=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7917-237x300.jpg\" srcset=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7917-237x300.jpg 237w,https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7917-1620x2048.jpg 1620w,https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7917-scaled.jpg 2024w\" sizes=\"auto, 250px\" title=\"\"><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36784\" target=\"_blank\"><img decoding=\"async\" alt=\"Menschen spielen Cricket in der Halle.\" width=\"300\" height=\"288\" loading=\"lazy\" src=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7911-300x288.jpg\" srcset=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7911-300x288.jpg 300w,https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7911-2048x1964.jpg 2048w,https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7911-scaled.jpg 2560w\" sizes=\"auto, 250px\" title=\"\"><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36783\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"225\" height=\"300\" loading=\"lazy\" src=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7909-225x300.jpg\" srcset=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7909-225x300.jpg 225w,https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7909-1536x2048.jpg 1536w,https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7909-scaled.jpg 1920w\" sizes=\"auto, 250px\" title=\"\"><\/a><\/div><\/div><\/noscript><\/div><script type=\"application\/json\" class=\"sgb-data\">{\"galleryType\":\"pgc_sgb_viewer\",\"galleryId\":\"edf63700\",\"images\":[{\"id\":36787,\"title\":\"IMG_E7950\",\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7950-scaled.jpg\",\"link\":\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36787\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":2560,\"height\":1920,\"sizes\":{\"thumbnail\":{\"height\":113,\"width\":150,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7950-150x113.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7950-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":1536,\"width\":2048,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7950-2048x1536.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7950-scaled.jpg\",\"height\":1920,\"width\":2560,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36787\"},{\"id\":36786,\"title\":\"IMG_E7933\",\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7933-scaled.jpg\",\"link\":\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36786\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":2107,\"height\":2560,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":123,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7933-123x150.jpg\",\"orientation\":\"portrait\"},\"medium\":{\"height\":300,\"width\":247,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7933-247x300.jpg\",\"orientation\":\"portrait\"},\"large\":{\"height\":2048,\"width\":1685,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7933-1685x2048.jpg\",\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7933-scaled.jpg\",\"height\":2560,\"width\":2107,\"orientation\":\"portrait\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36786\"},{\"id\":36785,\"title\":\"IMG_E7917\",\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7917-scaled.jpg\",\"link\":\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36785\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":2024,\"height\":2560,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":119,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7917-119x150.jpg\",\"orientation\":\"portrait\"},\"medium\":{\"height\":300,\"width\":237,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7917-237x300.jpg\",\"orientation\":\"portrait\"},\"large\":{\"height\":2048,\"width\":1620,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7917-1620x2048.jpg\",\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7917-scaled.jpg\",\"height\":2560,\"width\":2024,\"orientation\":\"portrait\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36785\"},{\"id\":36784,\"title\":\"IMG_E7911\",\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7911-scaled.jpg\",\"link\":\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36784\",\"alt\":\"Menschen spielen Cricket in der Halle.\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":2560,\"height\":2455,\"sizes\":{\"thumbnail\":{\"height\":144,\"width\":150,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7911-150x144.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":288,\"width\":300,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7911-300x288.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":1964,\"width\":2048,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7911-2048x1964.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7911-scaled.jpg\",\"height\":2455,\"width\":2560,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36784\"},{\"id\":36783,\"title\":\"IMG_E7909\",\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7909-scaled.jpg\",\"link\":\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36783\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1920,\"height\":2560,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":113,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7909-113x150.jpg\",\"orientation\":\"portrait\"},\"medium\":{\"height\":300,\"width\":225,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7909-225x300.jpg\",\"orientation\":\"portrait\"},\"large\":{\"height\":2048,\"width\":1536,\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7909-1536x2048.jpg\",\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG_E7909-scaled.jpg\",\"height\":2560,\"width\":1920,\"orientation\":\"portrait\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.hs-nordhausen.de\/?attachment_id=36783\"}],\"className\":\"\",\"TrpContentRestriction\":{\"restriction_type\":\"exclude\",\"selected_languages\":[],\"panel_open\":true},\"itemsMetaDataCollection\":[]}<\/script><script>(function(){if(window.PGC_SGB && window.PGC_SGB.searcher){window.PGC_SGB.searcher.initBlocks()}})()<\/script><\/div>\n\n\n<p><strong>Nach einer kurzen Einf\u00fchrung ins Cricket-Spiel durch Nicola Bargfrede konnte das Gelernte sportlich angewendet und Spielz\u00fcge analysiert werden. Nach interessanten Unternehmensvorstellungen wurde der Austausch in einem informellen Rahmenprogramm vertieft. (Fotos: Wille\/HSN)<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"525\" height=\"349\" src=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/1.jpg\" alt=\"\" class=\"wp-image-36788\" style=\"width:400px\" title=\"\" srcset=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/1.jpg 525w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/1-300x199.jpg 300w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/1-150x100.jpg 150w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/1-18x12.jpg 18w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/1-24x16.jpg 24w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"821\" height=\"298\" src=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/2.jpg\" alt=\"\" class=\"wp-image-36789\" style=\"width:450px\" title=\"\" srcset=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/2.jpg 821w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/2-300x109.jpg 300w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/2-150x54.jpg 150w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/2-768x279.jpg 768w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/2-18x7.jpg 18w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/2-24x9.jpg 24w\" sizes=\"(max-width: 821px) 100vw, 821px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>After a brief introduction to the game of cricket by Nicola Bargfrede, the participants were able to put what they had learned into practice and analyse moves. After interesting company presentations, the exchange was deepened in an informal framework programme. (Photos: Wille\/HSN)<\/p>","protected":false},"featured_media":36784,"template":"","meta":{"_piecal_is_recurring":false,"_piecal_recurring_interval":1,"_piecal_recurring_frequency":"","_piecal_recurring_exact_position":false,"_piecal_recurring_end":"","_piecal_color":"","_piecal_text_color":"","_piecal_global_color_master":false,"_piecal_rsets":"[]","_piecal_is_event":true,"_piecal_start_date":"2025-11-10T09:49:44","_piecal_end_date":"2025-11-10T09:49:46","_piecal_is_allday":false,"greyd_block_editor_preview":[],"pgc_sgb_lightbox_settings":""},"pressemitteilungen_category":[1298],"pressemitteilungen_tag":[],"zielgruppen":[1870],"kontakt-zuordnung":[2001],"projekt":[1422],"studienbereich":[868],"institut-oder-einric":[736],"stg-zuordnung":[696],"fachbereich":[804],"wf_pressemitteilungen_folders":[2657],"ppma_author":[1400],"class_list":["post-36782","pressemitteilungen","type-pressemitteilungen","status-publish","has-post-thumbnail","hentry","pressemitteilungen_category-pm-aktuell","zielgruppen-alle-interessierten","kontakt-zuordnung-n-a","projekt-n-a","studienbereich-n-a","institut-oder-einric-n-a","stg-zuordnung-n-a","fachbereich-n-a"],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen\/36782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen"}],"about":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/types\/pressemitteilungen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media\/36784"}],"wp:attachment":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media?parent=36782"}],"wp:term":[{"taxonomy":"pressemitteilungen_category","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen_category?post=36782"},{"taxonomy":"pressemitteilungen_tag","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen_tag?post=36782"},{"taxonomy":"zielgruppen","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/zielgruppen?post=36782"},{"taxonomy":"kontakt-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/kontakt-zuordnung?post=36782"},{"taxonomy":"projekt","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/projekt?post=36782"},{"taxonomy":"studienbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studienbereich?post=36782"},{"taxonomy":"institut-oder-einric","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/institut-oder-einric?post=36782"},{"taxonomy":"stg-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/stg-zuordnung?post=36782"},{"taxonomy":"fachbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/fachbereich?post=36782"},{"taxonomy":"wf_pressemitteilungen_folders","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/wf_pressemitteilungen_folders?post=36782"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/ppma_author?post=36782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}