{"id":36818,"date":"2025-11-12T14:05:11","date_gmt":"2025-11-12T13:05:11","guid":{"rendered":"https:\/\/www.hs-nordhausen.de\/?post_type=pressemitteilungen&#038;p=36818"},"modified":"2025-11-12T14:06:38","modified_gmt":"2025-11-12T13:06:38","slug":"research-team-from-nordhausen-university-of-applied-sciences-receives-thuringia-research-award-2025","status":"publish","type":"pressemitteilungen","link":"https:\/\/www.hs-nordhausen.de\/en\/pressemitteilungen\/forschungsteam-der-hochschule-nordhausen-erhaelt-thueringer-forschungspreis-2025\/","title":{"rendered":"Research team from Nordhausen University of Applied Sciences receives Thuringian Research Award 2025"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG-20251111-WA0005.jpg\" alt=\"Group photo with awards and flowers.\" class=\"wp-image-36820\" title=\"\" srcset=\"https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG-20251111-WA0005.jpg 2048w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG-20251111-WA0005-300x225.jpg 300w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG-20251111-WA0005-150x113.jpg 150w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG-20251111-WA0005-768x576.jpg 768w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG-20251111-WA0005-1536x1152.jpg 1536w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG-20251111-WA0005-16x12.jpg 16w, https:\/\/www.hs-nordhausen.de\/wp-content\/uploads\/sites\/8\/2025\/11\/IMG-20251111-WA0005-24x18.jpg 24w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><figcaption class=\"wp-element-caption\"><strong>Minister Christinan Tischner (far left) and jury chairman Prof Dr Dieter Br\u00fcggemann (far right) with the award winners.<\/strong> (Photo: HSN)<\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":36820,"template":"","meta":{"_piecal_is_recurring":false,"_piecal_recurring_interval":1,"_piecal_recurring_frequency":"","_piecal_recurring_exact_position":false,"_piecal_recurring_end":"","_piecal_color":"","_piecal_text_color":"","_piecal_global_color_master":false,"_piecal_rsets":"[]","_piecal_is_event":true,"_piecal_start_date":"2025-11-12T14:04:27","_piecal_end_date":"2025-11-12T14:04:30","_piecal_is_allday":false,"greyd_block_editor_preview":[],"pgc_sgb_lightbox_settings":""},"pressemitteilungen_category":[1298],"pressemitteilungen_tag":[],"zielgruppen":[1870],"kontakt-zuordnung":[2019],"projekt":[1419],"studienbereich":[810],"institut-oder-einric":[736],"stg-zuordnung":[696],"fachbereich":[583],"wf_pressemitteilungen_folders":[2657],"ppma_author":[1400],"class_list":["post-36818","pressemitteilungen","type-pressemitteilungen","status-publish","has-post-thumbnail","hentry","pressemitteilungen_category-pm-aktuell","zielgruppen-alle-interessierten","kontakt-zuordnung-ehinz","projekt-carbomass","studienbereich-it-technik-ingenieurwissenschaften","institut-oder-einric-n-a","stg-zuordnung-n-a","fachbereich-fb-ingenieurwissenschaften"],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen\/36818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen"}],"about":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/types\/pressemitteilungen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media\/36820"}],"wp:attachment":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media?parent=36818"}],"wp:term":[{"taxonomy":"pressemitteilungen_category","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen_category?post=36818"},{"taxonomy":"pressemitteilungen_tag","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/pressemitteilungen_tag?post=36818"},{"taxonomy":"zielgruppen","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/zielgruppen?post=36818"},{"taxonomy":"kontakt-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/kontakt-zuordnung?post=36818"},{"taxonomy":"projekt","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/projekt?post=36818"},{"taxonomy":"studienbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studienbereich?post=36818"},{"taxonomy":"institut-oder-einric","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/institut-oder-einric?post=36818"},{"taxonomy":"stg-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/stg-zuordnung?post=36818"},{"taxonomy":"fachbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/fachbereich?post=36818"},{"taxonomy":"wf_pressemitteilungen_folders","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/wf_pressemitteilungen_folders?post=36818"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/ppma_author?post=36818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}