{"id":317,"date":"2023-03-02T11:59:24","date_gmt":"2023-03-02T10:59:24","guid":{"rendered":"https:\/\/hsnordhausen.artemis.wpspace.me\/hsn\/studienangebote\/bachelor\/internationale-betriebswirtschaft\/"},"modified":"2025-10-30T14:00:54","modified_gmt":"2025-10-30T13:00:54","slug":"international-business-administration","status":"publish","type":"studiengaenge","link":"https:\/\/www.hs-nordhausen.de\/en\/studiengaenge\/internationale-betriebswirtschaft\/","title":{"rendered":"International Business Administration"},"content":{"rendered":"<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":15941,"template":"","meta":{"_piecal_is_recurring":false,"_piecal_recurring_interval":1,"_piecal_recurring_frequency":"","_piecal_recurring_exact_position":false,"_piecal_recurring_end":"","_piecal_color":"","_piecal_text_color":"","_piecal_global_color_master":false,"_piecal_rsets":"[]","_piecal_is_event":false,"_piecal_start_date":"","_piecal_end_date":"","_piecal_is_allday":false,"greyd_block_editor_preview":{"enabled":true,"maxWidth":"1200px","backgroundColor":""},"pgc_sgb_lightbox_settings":""},"studiengaenge_category":[887,90,2628],"studiengaenge_tag":[922],"studiengaenge_studienformat":[2808,888,318],"studiengaenge_lehrsprache":[273,274],"studiengaenge_abschluss":[704],"studiengangsleitung":[2208],"zielgruppen":[],"kontakt-zuordnung":[2121],"projekt":[1422],"studienbereich":[806],"institut-oder-einric":[1383],"stg-zuordnung":[650],"zusatzbereiche":[854],"fachbereich":[591],"wf_studiengaenge_folders":[2933],"ppma_author":[1400],"class_list":["post-317","studiengaenge","type-studiengaenge","status-publish","has-post-thumbnail","hentry","studiengaenge_category-fb-wirtschafts-und-sozialwissenschaften","studiengaenge_category-management","studiengaenge_category-wird-nicht-mehr-angeboten","studiengaenge_tag-ibw","studiengaenge_studienformat-praesenz","studiengaenge_studienformat-studium-praxis","studiengaenge_studienformat-vollzeitstudium","studiengaenge_lehrsprache-deutsch","studiengaenge_lehrsprache-englisch","studiengaenge_abschluss-bachelor","studiengangsleitung-studiengangsleitung-ibw","kontakt-zuordnung-rwagner","projekt-n-a","studienbereich-betriebswirtschaftslehre","institut-oder-einric-dich-institut-fuer-digitalisierung-innovation-und-change","stg-zuordnung-ibw","zusatzbereiche-ibw","fachbereich-fb-wirtschafts-und-sozialwissenschaften"],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge\/317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge"}],"about":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/types\/studiengaenge"}],"author":[{"embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media\/15941"}],"wp:attachment":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media?parent=317"}],"wp:term":[{"taxonomy":"studiengaenge_category","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge_category?post=317"},{"taxonomy":"studiengaenge_tag","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge_tag?post=317"},{"taxonomy":"studiengaenge_studienformat","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge_studienformat?post=317"},{"taxonomy":"studiengaenge_lehrsprache","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge_lehrsprache?post=317"},{"taxonomy":"studiengaenge_abschluss","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge_abschluss?post=317"},{"taxonomy":"studiengangsleitung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengangsleitung?post=317"},{"taxonomy":"zielgruppen","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/zielgruppen?post=317"},{"taxonomy":"kontakt-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/kontakt-zuordnung?post=317"},{"taxonomy":"projekt","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/projekt?post=317"},{"taxonomy":"studienbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studienbereich?post=317"},{"taxonomy":"institut-oder-einric","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/institut-oder-einric?post=317"},{"taxonomy":"stg-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/stg-zuordnung?post=317"},{"taxonomy":"zusatzbereiche","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/zusatzbereiche?post=317"},{"taxonomy":"fachbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/fachbereich?post=317"},{"taxonomy":"wf_studiengaenge_folders","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/wf_studiengaenge_folders?post=317"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/ppma_author?post=317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}