{"id":652,"date":"2023-04-06T12:05:57","date_gmt":"2023-04-06T11:05:57","guid":{"rendered":"https:\/\/hsnordhausen.artemis.wpspace.me\/hsn\/studienangebote\/master\/innovations-und-changemanagement\/"},"modified":"2026-03-27T13:26:33","modified_gmt":"2026-03-27T12:26:33","slug":"innovation-and-change-management","status":"publish","type":"studiengaenge","link":"https:\/\/www.hs-nordhausen.de\/en\/studiengaenge\/innovations-und-changemanagement\/","title":{"rendered":"Innovation and change management"},"content":{"rendered":"<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":16030,"template":"","meta":{"_piecal_is_recurring":false,"_piecal_recurring_interval":1,"_piecal_recurring_frequency":"","_piecal_recurring_exact_position":false,"_piecal_recurring_end":"","_piecal_color":"","_piecal_text_color":"","_piecal_global_color_master":false,"_piecal_rsets":"[]","_piecal_is_event":false,"_piecal_start_date":"","_piecal_end_date":"","_piecal_is_allday":false,"greyd_block_editor_preview":[],"pgc_sgb_lightbox_settings":""},"studiengaenge_category":[887,90],"studiengaenge_tag":[1515],"studiengaenge_studienformat":[2916,2808,888,318],"studiengaenge_lehrsprache":[273],"studiengaenge_abschluss":[705],"studiengangsleitung":[2219],"zielgruppen":[],"kontakt-zuordnung":[],"projekt":[1422],"studienbereich":[806],"institut-oder-einric":[1383],"stg-zuordnung":[649],"zusatzbereiche":[853],"fachbereich":[591],"wf_studiengaenge_folders":[2934],"ppma_author":[1400],"class_list":["post-652","studiengaenge","type-studiengaenge","status-publish","has-post-thumbnail","hentry","studiengaenge_category-fb-wirtschafts-und-sozialwissenschaften","studiengaenge_category-management","studiengaenge_tag-icm","studiengaenge_studienformat-hybrid","studiengaenge_studienformat-praesenz","studiengaenge_studienformat-studium-praxis","studiengaenge_studienformat-vollzeitstudium","studiengaenge_lehrsprache-deutsch","studiengaenge_abschluss-master","studiengangsleitung-studiengangsleitung-icm","projekt-n-a","studienbereich-betriebswirtschaftslehre","institut-oder-einric-dich-institut-fuer-digitalisierung-innovation-und-change","stg-zuordnung-icm","zusatzbereiche-icm","fachbereich-fb-wirtschafts-und-sozialwissenschaften"],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge\/652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge"}],"about":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/types\/studiengaenge"}],"author":[{"embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media\/16030"}],"wp:attachment":[{"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/media?parent=652"}],"wp:term":[{"taxonomy":"studiengaenge_category","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge_category?post=652"},{"taxonomy":"studiengaenge_tag","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge_tag?post=652"},{"taxonomy":"studiengaenge_studienformat","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge_studienformat?post=652"},{"taxonomy":"studiengaenge_lehrsprache","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge_lehrsprache?post=652"},{"taxonomy":"studiengaenge_abschluss","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengaenge_abschluss?post=652"},{"taxonomy":"studiengangsleitung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studiengangsleitung?post=652"},{"taxonomy":"zielgruppen","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/zielgruppen?post=652"},{"taxonomy":"kontakt-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/kontakt-zuordnung?post=652"},{"taxonomy":"projekt","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/projekt?post=652"},{"taxonomy":"studienbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/studienbereich?post=652"},{"taxonomy":"institut-oder-einric","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/institut-oder-einric?post=652"},{"taxonomy":"stg-zuordnung","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/stg-zuordnung?post=652"},{"taxonomy":"zusatzbereiche","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/zusatzbereiche?post=652"},{"taxonomy":"fachbereich","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/fachbereich?post=652"},{"taxonomy":"wf_studiengaenge_folders","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/wf_studiengaenge_folders?post=652"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.hs-nordhausen.de\/en\/wp-json\/wp\/v2\/ppma_author?post=652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}